{"id":1465,"date":"2024-01-05T15:48:02","date_gmt":"2024-01-05T14:48:02","guid":{"rendered":"https:\/\/metsens.fr\/traiteur\/?page_id=1465"},"modified":"2024-01-05T15:49:20","modified_gmt":"2024-01-05T14:49:20","slug":"greenhouse","status":"publish","type":"page","link":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/","title":{"rendered":"Greenhouse"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1465\" class=\"elementor elementor-1465\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dbae772 e-con-full e-flex e-con e-parent\" data-id=\"6dbae772\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1804e105 e-con-full e-flex e-con e-child\" data-id=\"1804e105\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1eda42d4 elementor-widget elementor-widget-heading\" data-id=\"1eda42d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">THE METSENS GREENHOUSE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2af4347 elementor-widget elementor-widget-heading\" data-id=\"2af4347\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels.\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-685a8fc9 elementor-widget elementor-widget-text-editor\" data-id=\"685a8fc9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and waste reduction.<\/p><p>Aquaponics?<\/p><p>Aquaponics is the cultivation of fish and plants together in a closed-loop ecosystem, using natural bacterial cycles to transform fish waste into nutrients for plants. It is an ecological and natural way of producing food that combines the best qualities of aquaculture and hydroponics, without the need to discharge water, filter it, or use chemical fertilizers.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a20aabe elementor-widget elementor-widget-image\" data-id=\"5a20aabe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"409\" src=\"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2024\/01\/MS-9345-scaled-e1704366637915-1024x524.webp\" class=\"attachment-large size-large wp-image-955\" alt=\"\" srcset=\"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2024\/01\/MS-9345-scaled-e1704366637915-1024x524.webp 1024w, https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2024\/01\/MS-9345-scaled-e1704366637915-300x153.webp 300w, https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2024\/01\/MS-9345-scaled-e1704366637915-768x393.webp 768w, https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2024\/01\/MS-9345-scaled-e1704366637915-1536x785.webp 1536w, https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2024\/01\/MS-9345-scaled-e1704366637915.webp 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f33464d elementor-widget elementor-widget-text-editor\" data-id=\"f33464d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1531082052776\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><p>In memory of my friend Fran\u00e7ois.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1535566242784\"><div class=\"wpb_wrapper\">\u00a0<\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4525ed e-con-full e-flex e-con e-child\" data-id=\"a4525ed\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-1465","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Metsens Traiteur Marseille - Metsens Traiteur Mariage buffets\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Greenhouse - Metsens Traiteur Marseille\" \/>\n\t\t<meta property=\"og:description\" content=\"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/logo-noir.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/logo-noir.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-01-05T14:48:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-05T14:49:20+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/metsens.traiteur\/?locale=fr_FR\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Greenhouse - Metsens Traiteur Marseille\" \/>\n\t\t<meta name=\"twitter:description\" content=\"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/logo-noir.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/#listItem\",\"position\":1,\"name\":\"Greenhouse\"}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/#organization\",\"name\":\"Metsens Traiteur Marseille\",\"description\":\"Metsens Traiteur Mariage buffets\",\"url\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/\",\"telephone\":\"+33496218414\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-logo-noir.webp\",\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/#organizationLogo\",\"width\":1920,\"height\":1151,\"caption\":\"Metsens traiteur marseille\"},\"image\":{\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/metsens.traiteur\\\/?locale=fr_FR\",\"https:\\\/\\\/www.instagram.com\\\/metsens\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@MetsensTraiteuraMarseille\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/metsens-traiteur\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/#webpage\",\"url\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/\",\"name\":\"Greenhouse - Metsens Traiteur Marseille\",\"description\":\"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/en\\\/greenhouse\\\/#breadcrumblist\"},\"datePublished\":\"2024-01-05T15:48:02+01:00\",\"dateModified\":\"2024-01-05T15:49:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/#website\",\"url\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/\",\"name\":\"Metsens Traiteur Marseille\",\"alternateName\":\"METSENS\",\"description\":\"Metsens Traiteur Mariage buffets\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/metsens.fr\\\/traiteur\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Greenhouse - Metsens Traiteur Marseille","description":"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and","canonical_url":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/#listItem","position":1,"name":"Greenhouse"}]},{"@type":"Organization","@id":"https:\/\/metsens.fr\/traiteur\/#organization","name":"Metsens Traiteur Marseille","description":"Metsens Traiteur Mariage buffets","url":"https:\/\/metsens.fr\/traiteur\/","telephone":"+33496218414","logo":{"@type":"ImageObject","url":"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/cropped-logo-noir.webp","@id":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/#organizationLogo","width":1920,"height":1151,"caption":"Metsens traiteur marseille"},"image":{"@id":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/metsens.traiteur\/?locale=fr_FR","https:\/\/www.instagram.com\/metsens\/","https:\/\/www.youtube.com\/@MetsensTraiteuraMarseille","https:\/\/www.linkedin.com\/company\/metsens-traiteur\/"]},{"@type":"WebPage","@id":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/#webpage","url":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/","name":"Greenhouse - Metsens Traiteur Marseille","description":"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/metsens.fr\/traiteur\/#website"},"breadcrumb":{"@id":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/#breadcrumblist"},"datePublished":"2024-01-05T15:48:02+01:00","dateModified":"2024-01-05T15:49:20+01:00"},{"@type":"WebSite","@id":"https:\/\/metsens.fr\/traiteur\/#website","url":"https:\/\/metsens.fr\/traiteur\/","name":"Metsens Traiteur Marseille","alternateName":"METSENS","description":"Metsens Traiteur Mariage buffets","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/metsens.fr\/traiteur\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Metsens Traiteur Marseille - Metsens Traiteur Mariage buffets","og:type":"article","og:title":"Greenhouse - Metsens Traiteur Marseille","og:description":"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and","og:url":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/","og:image":"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/logo-noir.webp","og:image:secure_url":"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/logo-noir.webp","article:published_time":"2024-01-05T14:48:02+00:00","article:modified_time":"2024-01-05T14:49:20+00:00","article:publisher":"https:\/\/www.facebook.com\/metsens.traiteur\/?locale=fr_FR","twitter:card":"summary_large_image","twitter:title":"Greenhouse - Metsens Traiteur Marseille","twitter:description":"THE METSENS GREENHOUSE Continuously striving to improve our CSR policy, Maison Metsens presents its connected aquaponic greenhouse. Self-sufficient in electricity thanks to solar panels. The goal is to produce our own aromatic herbs and edible flowers on the rooftops of Allauch: short circuit, product quality and freshness, reduced environmental impact, strengthening the value chain, and","twitter:image":"https:\/\/metsens.fr\/traiteur\/wp-content\/uploads\/2023\/12\/logo-noir.webp"},"aioseo_meta_data":{"post_id":"1465","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-12 15:02:05","updated":"2025-06-04 00:41:41","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/\" title=\"Greenhouse\">Greenhouse<\/a>\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Greenhouse","link":"https:\/\/metsens.fr\/traiteur\/en\/greenhouse\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/pages\/1465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/comments?post=1465"}],"version-history":[{"count":7,"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/pages\/1465\/revisions"}],"predecessor-version":[{"id":1472,"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/pages\/1465\/revisions\/1472"}],"wp:attachment":[{"href":"https:\/\/metsens.fr\/traiteur\/wp-json\/wp\/v2\/media?parent=1465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}